{"id":697,"date":"2013-07-05T22:12:37","date_gmt":"2013-07-05T20:12:37","guid":{"rendered":"http:\/\/www.tunnelblick.es\/press\/?p=697"},"modified":"2013-07-05T22:13:07","modified_gmt":"2013-07-05T20:13:07","slug":"37-lasst-die-filder-leben","status":"publish","type":"post","link":"http:\/\/www.tunnelblick.es\/press\/2013\/07\/37-lasst-die-filder-leben\/","title":{"rendered":"#37: Lasst die Filder leben!"},"content":{"rendered":"<p><a href=\"http:\/\/www.tunnelblick.es\/press\/wp-content\/uploads\/2013\/07\/ES21_Tunnelblick-37.png\" rel=\"shadowbox[sbpost-697];player=img;\"><img loading=\"lazy\" src=\"http:\/\/www.tunnelblick.es\/press\/wp-content\/uploads\/2013\/07\/ES21_Tunnelblick-37-212x300.png\" alt=\"Tunnelblick 37\" width=\"212\" height=\"300\" class=\"alignleft size-medium wp-image-698\" srcset=\"http:\/\/www.tunnelblick.es\/press\/wp-content\/uploads\/2013\/07\/ES21_Tunnelblick-37-212x300.png 212w, http:\/\/www.tunnelblick.es\/press\/wp-content\/uploads\/2013\/07\/ES21_Tunnelblick-37.png 750w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a>Die Filder, einst l\u00e4ndliche Idylle und einzigartiges, fruchtbares Ackerland, wurden in den vergangenen Jahrzehnten mehr und mehr zur Verf\u00fcgungsmasse f\u00fcr Gro\u00dfprojekte \u2013 im Namen eines angeblichen technologischen und wirtschaftlichen Fortschritts. Heute \u00fcberzieht ein dichtes Stra\u00dfennetz die Hochebene vor den Toren Stuttgarts. Der Flughafen wurde ausgebaut und bringt die Menschen um ihre Ruhe. Auch f\u00fcr die neue Messe wurde wertvolles Ackerland zubetoniert. Nun droht weitere Zerst\u00f6rung durch das Milliardenprojekt Stuttgart 21. Doch die Filderbewohner wehren sich.<br \/>\n<a href=\"http:\/\/www.tunnelblick.es\/press\/wp-content\/uploads\/2013\/07\/ES21_Tunnelblick-37_s.pdf\">Tunnelblick 37 (Webausgabe)<\/a><br \/>\n<a href=\"http:\/\/www.tunnelblick.es\/press\/wp-content\/uploads\/2013\/07\/ES21_Tunnelblick-37.pdf\">Tunnelblick 37 (Druckdatei)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Filder, einst l\u00e4ndliche Idylle und einzigartiges, fruchtbares Ackerland, wurden in den vergangenen Jahrzehnten mehr und mehr zur Verf\u00fcgungsmasse f\u00fcr Gro\u00dfprojekte \u2013 im Namen eines angeblichen technologischen und wirtschaftlichen Fortschritts. Heute \u00fcberzieht ein dichtes Stra\u00dfennetz die Hochebene vor den Toren &hellip; <a href=\"http:\/\/www.tunnelblick.es\/press\/2013\/07\/37-lasst-die-filder-leben\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/posts\/697"}],"collection":[{"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/comments?post=697"}],"version-history":[{"count":5,"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/posts\/697\/revisions"}],"predecessor-version":[{"id":705,"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/posts\/697\/revisions\/705"}],"wp:attachment":[{"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/media?parent=697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/categories?post=697"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.tunnelblick.es\/press\/wp-json\/wp\/v2\/tags?post=697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}